{"id":4310,"date":"2023-04-03T20:11:11","date_gmt":"2023-04-04T01:11:11","guid":{"rendered":"http:\/\/pppnet.net\/?p=3933"},"modified":"2023-04-24T01:27:14","modified_gmt":"2023-04-24T06:27:14","slug":"early-prophecy-on-confined-walls-in-russia-ukraine-war","status":"publish","type":"post","link":"https:\/\/pppnet.net\/ko\/early-prophecy-on-confined-walls-in-russia-ukraine-war\/","title":{"rendered":"\uc774\ub974\uba74 2022\ub144 4\uc6d4 26\uc77c, \ub7ec\uc2dc\uc544-\uc6b0\ud06c\ub77c\uc774\ub098 \uc804\uc7c1\uc5d0\uc11c \uad6d\uacbd \uc7a5\ubcbd\uc744 \uc608\uce21\ud558\ub2e4"},"content":{"rendered":"<h2><span class=\"ez-toc-section\" id=\"2022%E5%B9%B44%E6%9C%8826%E6%97%A5%E7%9A%84%E6%8F%90%E4%BA%A4%E8%A8%98%E9%8C%84\"><\/span><span style=\"color: #0000ff;\">\uc81c\ucd9c \uae30\ub85d \ub0a0\uc9dc: 2022\ub144 4\uc6d4 26\uc77c<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div id='gallery-1' class='gallery galleryid-4310 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/pppnet.net\/ko\/walls-in-russia-ukraine-war-predicted-on-april-26-2022\/22-04-26-59k\/'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/pppnet.net\/wp-content\/uploads\/2023\/04\/22-04-26-59K-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Confined Walls in Russia-Ukraine War\/from PPPNET\" aria-describedby=\"gallery-1-3857\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3857'>\n\t\t\t\t2022 \ub144 4 \uc6d4 26 \uc77c, \ub7ec\uc2dc\uc544-\uc6b0\ud06c\ub77c\uc774\ub098 \uc804\uc7c1\uc774 \ub450 \uac1c\uc758 \uad6d\uacbd \uc7a5\ubcbd\uc5d0 \uac07\ud790 \uac83\uc73c\ub85c \uc608\uc0c1 \ub428\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/pppnet.net\/ko\/walls-in-russia-ukraine-war-predicted-on-april-26-2022\/3linemay23\/'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/pppnet.net\/wp-content\/uploads\/2023\/04\/3lineMay23-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"3 ceasefire lines\/from PPPNET\" aria-describedby=\"gallery-1-3858\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3858'>\n\t\t\t\t2022\ub144 5\uc6d4 23\uc77c, \ub7ec\uc2dc\uc544-\uc6b0\ud06c\ub77c\uc774\ub098 \uc804\uc7c1\uc758 \uc138 \ud734\uc804\uc120\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/pppnet.net\/ko\/early-prophecy-on-confined-walls-in-russia-ukraine-war\/cn2walls\/'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/pppnet.net\/wp-content\/uploads\/2023\/04\/cn2walls-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Ukraine War Trend Prediction by2026 BY PPPNET\" aria-describedby=\"gallery-1-4528\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-4528'>\n\t\t\t\t\uc804\uc7a5\uc758 \uad6d\uacbd \uc7a5\ubcbd\uacfc \uadf9\uc7a5 \ud2b8\ub80c\ub4dc \uc0c1\uc0c1\ud558\uae30 \/ \ub7ec-\uc6b0\ud06c\ub77c\uc774\ub098 \uc804\uc7c1 \/ PPPNET\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p style=\"text-align: left;\">\uc6d0\ubcf8 \uae30\uc0ac\uac00 \uc190\uc2e4\ub418\uc5c8\uc2b5\ub2c8\ub2e4. \ub7ec\uc2dc\uc544-\uc6b0\ud06c\ub77c\uc774\ub098 \uc804\uc7c1\uc758 \uad6d\uacbd \uc7a5\ubcbd\uc5d0 \ub300\ud55c \uac00\uc7a5 \ube60\ub978 \uc608\uce21\uc774 2022\ub144 4\uc6d4 26\uc77c\uc5d0 \uc774\ub8e8\uc5b4\uc84c\ub2e4\ub294 \uac83\uc744 \ubcf4\uc5ec\uc8fc\ub294 \uc81c\ucd9c\ubb3c\uc744 \uc6b0\uc5f0\ud788 \ubc1c\uacac\ud588\uc2b5\ub2c8\ub2e4. \uc774\ubc88\uc5d0\ub294 \ub7ec\uc2dc\uc544 \ud2b9\ubcc4 \uad70\uc0ac \ucea0\ud398\uc778\uc758 \uccab \ubc88\uc9f8 \ub2e8\uacc4\uac00 \ub05d\ub0a0 \ubb34\ub835\uc785\ub2c8\ub2e4.<br \/>\n\uc774 \uae30\ub85d \uc81c\ucd9c\uc5d0\ub294 \uc138 \uac00\uc9c0 \ud575\uc2ec \uc0ac\ud56d\uc774 \uc788\uc2b5\ub2c8\ub2e4.<\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 ez-toc-wrap-right counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\ubaa9\ucc28<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\ubaa9\ucc28 \ud1a0\uae00\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">\ud1a0\uae00<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/pppnet.net\/ko\/early-prophecy-on-confined-walls-in-russia-ukraine-war\/#2022%E5%B9%B44%E6%9C%8826%E6%97%A5%E7%9A%84%E6%8F%90%E4%BA%A4%E8%A8%98%E9%8C%84\" >\uc81c\ucd9c \uae30\ub85d \ub0a0\uc9dc: 2022\ub144 4\uc6d4 26\uc77c<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/pppnet.net\/ko\/early-prophecy-on-confined-walls-in-russia-ukraine-war\/#%E4%B8%89%E5%80%8B%E8%A6%81%E9%BB%9E%EF%BC%9A\" >\uc138 \uac00\uc9c0 \ud575\uc2ec \uc0ac\ud56d:<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/pppnet.net\/ko\/early-prophecy-on-confined-walls-in-russia-ukraine-war\/#1_%E7%90%86%E8%AB%96%E4%B8%8A%E6%9C%89%E4%B8%89%E6%A2%9D%E5%81%9C%E7%81%AB%E7%B7%9A\" >\uc774\ub860\uc801\uc73c\ub85c \ud734\uc804\uc120\uc5d0\ub294 \uc138 \uac00\uc9c0\uac00 \uc788\uc2b5\ub2c8\ub2e4.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/pppnet.net\/ko\/early-prophecy-on-confined-walls-in-russia-ukraine-war\/#2_%E7%BE%8E%E5%9C%8B%E6%98%AF%E5%81%9C%E7%81%AB%E5%95%8F%E9%A1%8C%E4%B8%8A%E7%9A%84%E6%9C%80%E5%BC%B7%E5%A4%A7%E7%9A%84%E5%8A%9B%E9%87%8F\" >2. \ubbf8\uad6d\uc740 \ud734\uc804 \ubb38\uc81c\uc5d0\uc11c \uac00\uc7a5 \uac15\ub825\ud55c \ud798\uc785\ub2c8\ub2e4.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/pppnet.net\/ko\/early-prophecy-on-confined-walls-in-russia-ukraine-war\/#3_%E5%8D%B0%E5%BA%A6%E7%9A%84%E5%88%86%E9%87%8F%E5%BE%88%E9%87%8D\" >3. \uc778\ub3c4\ub294 \ub9ce\uc740 \ube44\uc911\uc744 \ucc28\uc9c0\ud569\ub2c8\ub2e4.<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/pppnet.net\/ko\/early-prophecy-on-confined-walls-in-russia-ukraine-war\/#%E7%B8%BD%E7%B5%90%EF%BC%9A\" >\uacb0\ub860:<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/pppnet.net\/ko\/early-prophecy-on-confined-walls-in-russia-ukraine-war\/#%E9%99%84%E8%A8%BB\" >\ucc38\uace0.<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n<h2 style=\"text-align: left;\"><span class=\"ez-toc-section\" id=\"%E4%B8%89%E5%80%8B%E8%A6%81%E9%BB%9E%EF%BC%9A\"><\/span><span style=\"color: #0000ff;\">\uc138 \uac00\uc9c0 \ud575\uc2ec \uc0ac\ud56d:<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3 style=\"text-align: left;\"><span class=\"ez-toc-section\" id=\"1_%E7%90%86%E8%AB%96%E4%B8%8A%E6%9C%89%E4%B8%89%E6%A2%9D%E5%81%9C%E7%81%AB%E7%B7%9A\"><\/span>\uc774\ub860\uc801\uc73c\ub85c \ud734\uc804\uc120\uc5d0\ub294 \uc138 \uac00\uc9c0\uac00 \uc788\uc2b5\ub2c8\ub2e4.<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: left;\">(\uc804\uc7c1\uc774 \ub9c9 \uc2dc\uc791\ub41c \uc0c1\ud669\uc5d0\uc11c \ud734\uc804\uc744 \uc608\uce21\ud558\uae30\uc5d0\ub294 \ub108\ubb34 \uc774\ub974\uc9c0 \uc54a\ub098\uc694!)<br \/>\n1.1 L1 \ub77c\uc778\uc740 \ub4dc\ub124\ud504\ub974 \uac15\uc5d0 \uc758\ud574 \uacbd\uacc4\ub97c \uc774\ub8f9\ub2c8\ub2e4. (\ub2f9\uc2dc \ud751\ud574 \uc5f0\uc548\uc740 \ub17c\uc758\ub418\uc9c0 \uc54a\uc558\uc2b5\ub2c8\ub2e4). \uc81c\uac00 \ud751\ud574 \uc5f0\uc548\uc744 L1 \ud734\uc804\uc120\uc758 \uc77c\ubd80\ub85c \ucc98\uc74c \uc5b8\uae09\ud55c \uac83\uc740 2022\ub144 5\uc6d4 23\uc77c\uc774\uc5c8\uc2b5\ub2c8\ub2e4.<br \/>\n1.2 L2 \ub178\uc120\uc740 \ub3c4\ub124\uce20\ud06c\uc640 \ub8e8\ud55c\uc2a4\ud06c \uc0ac\uc774\uc758 \uc804\uccb4 \ud589\uc815 \uacbd\uacc4\uc120\uc785\ub2c8\ub2e4.<br \/>\n1.3 L3 \ub77c\uc778\uc740 L1 \ub77c\uc778\uacfc L2 \ub77c\uc778 \uc0ac\uc774\uc5d0 \uc704\uce58\ud55c \ud734\uc804\uc120\uc785\ub2c8\ub2e4.<\/p>\n<h3 style=\"text-align: left;\"><span class=\"ez-toc-section\" id=\"2_%E7%BE%8E%E5%9C%8B%E6%98%AF%E5%81%9C%E7%81%AB%E5%95%8F%E9%A1%8C%E4%B8%8A%E7%9A%84%E6%9C%80%E5%BC%B7%E5%A4%A7%E7%9A%84%E5%8A%9B%E9%87%8F\"><\/span>2. \ubbf8\uad6d\uc740 \ud734\uc804 \ubb38\uc81c\uc5d0\uc11c \uac00\uc7a5 \uac15\ub825\ud55c \ud798\uc785\ub2c8\ub2e4.<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: left;\">2.1 \ub2f9\uc2dc \ud734\uc804 \uc5ec\ubd80\uc640 \uc7a5\uc18c\ub97c \uacb0\uc815\ud558\ub294 \uac00\uc7a5 \uac15\ub825\ud55c \ud798\uc740 \ubbf8\uad6d\uc774\uba70, \ub7ec\uc2dc\uc544, \uc720\ub7fd\uc5f0\ud569, \uc911\uad6d\uc744 \uc81c\uc678\ud55c \ub2e4\ub978 \uad6d\uac00(\uad6c\uccb4\uc801\uc73c\ub85c \uc5f4\uac70\ub41c \uad6d\uac00 \uc81c\uc678)\ub294 \uc5c6\ub2e4\ub294 \uc9c0\uc801\uc774 \uc788\uc5c8\uc2b5\ub2c8\ub2e4.<br \/>\n2.1 \ubbf8\uad6d\uc758 \uc8fc\uc694 \ubaa9\ud45c\uac00 \ub7ec\uc2dc\uc544\ub97c \uc57d\ud654\uc2dc\ud0a4\uace0, \uc720\ub7fd\uc5f0\ud569\uc744 \uc57d\ud654\uc2dc\ud0a4\uace0, \ub7ec\uc2dc\uc544\uc640 \uc720\ub7fd\uc5f0\ud569\uc758 \uad00\uacc4\ub97c \ucc28\ub2e8\ud558\ub294 \uac83\uc774\ub77c\uba74, \ubbf8\uad6d\uc740 L1\uacfc L2 \uc0ac\uc774\uc758 \ube44\uad50\uc801 \uc548\uc815\uc801\uc778 \ud734\uc804\uc120\uc744 \uc120\ud0dd\ud560 \uac83\uc785\ub2c8\ub2e4.<br \/>\n2.2 \ubbf8\uad6d\uc758 \uc8fc\uc694 \ubaa9\ud45c\uac00 \ub7ec\uc2dc\uc544\ub97c \uacc4\uc18d \uc57d\ud654\uc2dc\ud0a4\uace0 EU\ub97c \uc57d\ud654\uc2dc\ud0a4\uba70 \uc720\ub7fd\uc5d0 \uc7a5\uae30\uc801\uc778 \ud63c\ub780\uc744 \uc57c\uae30\ud558\ub294 \uac83\uc774\ub77c\uba74 \ubbf8\uad6d\uc740 L3 \ub77c\uc778\uc758 \ubd88\uc548\uc815\ud55c \ud734\uc804\uc120\uc744 \uc120\ud0dd\ud560 \uac83\uc785\ub2c8\ub2e4.<\/p>\n<h3 style=\"text-align: left;\"><span class=\"ez-toc-section\" id=\"3_%E5%8D%B0%E5%BA%A6%E7%9A%84%E5%88%86%E9%87%8F%E5%BE%88%E9%87%8D\"><\/span>3. \uc778\ub3c4\ub294 \ub9ce\uc740 \ube44\uc911\uc744 \ucc28\uc9c0\ud569\ub2c8\ub2e4.<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\uc778\ub3c4\uac00 \uc774 \uc0ac\ud0dc\uc5d0 \uac1c\uc785\ud55c\ub2e4\uba74 \uad00\ub828\ub41c \ubaa8\ub4e0 \ub2f9\uc0ac\uc790\uc5d0\uac8c \ud070 \uc704\ud5d8\uc744 \ucd08\ub798\ud560 \uc218 \uc788\uc73c\uba70, \uc2ec\uc9c0\uc5b4 \uc81c3\ucc28 \uc138\uacc4\ub300\uc804\uc774 \ubc1c\ubc1c\ud560 \uc218\ub3c4 \uc788\uc2b5\ub2c8\ub2e4.<\/p>\n<p>(\uc774 \uc608\uc5b8\uc758 \uadfc\uac70\ub294 \ubb34\uc5c7\uc778\uac00\uc694?) \uc774 \uc608\uc5b8\uc758 \uadfc\uac70\ub294 \ubb34\uc5c7\uc778\uac00\uc694? \uc9c0\uae08\uc740 \uc57d\uac04 \ud63c\ub780\uc2a4\ub7fd\uc2b5\ub2c8\ub2e4. \ud558\uc9c0\ub9cc 2022\ub144 5\uc6d4 23\uc77c\uc758 \uc6d0\uace0\uc5d0\uc11c \uc800\ub294 \ub2e4\uc74c\uacfc \uac19\uc774 \uc5b8\uae09\ud588\uc2b5\ub2c8\ub2e4. \uc778\ub3c4\uac00 \ub3cc\uc544 \uc11c\uc11c \ub7ec\uc2dc\uc544 \uc81c\uc7ac\uc5d0 \ub3d9\ucc38\ud558\uba74 \ubbf8\uad6d\uc774 \uc911\uad6d\uacfc \ubd84\ub9ac\ub418\ub3c4\ub85d \uc7a5\ub824 \ud560 \uac83\uc785\ub2c8\ub2e4. \uadf8\ub7ec\uba74 \ubbf8\uad6d\uc740 \uc804 \uc138\uacc4\ub97c \ub450 \uac1c\uc758 \ud3c9\ud589 \ud55c \ubd80\ubd84\uc73c\ub85c \ub098\ub20c \uc218\uc788\ub294 \ub354 \ub9ce\uc740 \uc790\uc2e0\uac10\uc744 \uac16\uac8c \ub420 \uac83\uc785\ub2c8\ub2e4).<\/p>\n<h2 style=\"text-align: left;\"><span class=\"ez-toc-section\" id=\"%E7%B8%BD%E7%B5%90%EF%BC%9A\"><\/span><span style=\"color: #0000ff;\">\uacb0\ub860:<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: left;\">1. \uc804\ud22c\uc640 \ud734\uc804\uc740 \ubaa8\ub450 \ub450 \uac1c\uc758 \ud3d0\uc1c4\ub41c \ubcbd(L1 \ub77c\uc778\uacfc L2 \ub77c\uc778 \uc0ac\uc774) \uc548\uc5d0\uc11c \uc9c4\ud589\ub429\ub2c8\ub2e4.<br \/>\n2. \ud734\uc804\uc774 \uc788\uc744 \uac83\uc785\ub2c8\ub2e4.<br \/>\n3. \ub450 \uacbd\uacc4\ubcbd\uc758 \ud734\uc804 \uc0c1\ud0dc\ub294 \ube44\uad50\uc801 \uc548\uc815\uc801\uc785\ub2c8\ub2e4.<br \/>\n4. \ub450 \uacbd\uacc4\ubcbd \uc0ac\uc774\uc758 \ud734\uc804 \uc0c1\ud0dc\uac00 \ubd88\uc548\uc815\ud569\ub2c8\ub2e4.<br \/>\n5. \uc804\uc7a5\uc758 \uacb0\uc815\uc801\uc778 \ud798\uc740 \ub2e4\ub978 \uc5b4\ub5a4 \uad6d\uac00\ub3c4 \uc544\ub2cc \ubbf8\uad6d\uc785\ub2c8\ub2e4.<br \/>\n6. \uc804\uc7c1\uc758 \ubaa9\ud45c\ub294 \uc720\ub7fd\uc5f0\ud569\uc758 \uc57d\ud654, \ub7ec\uc2dc\uc544\uc758 \uc57d\ud654, \uc720\ub7fd\uc5f0\ud569\uacfc \ub7ec\uc2dc\uc544 \uac04\uc758 \uc5f0\uacb0\uace0\ub9ac \ub04a\uae30 \ub4f1\uc774\uc5c8\uc2b5\ub2c8\ub2e4.<br \/>\n7. \uc804\uc7c1\uc758 \ubaa9\uc801\uc740 \ubbf8\uad6d\uc774 \uacc4\uc18d\ud574\uc11c EU\ub97c \uc57d\ud654\uc2dc\ud0a4\uace0 \ub7ec\uc2dc\uc544\ub97c \uc57d\ud654\uc2dc\ud0a4\uace0 \uc720\ub7fd\uc758 \ud63c\ub780\uc744 \uacc4\uc18d \uc601\uc18d\ud654\uc2dc\ud0ac \uac83\uc774\ub77c\ub294 \uc810\uc744 \ubc30\uc81c\ud558\uc9c0 \uc54a\uc2b5\ub2c8\ub2e4.<br \/>\n8. \uc778\ub3c4\uc758 \ube44\uc911\uc774 \ub108\ubb34 \ucee4\uc11c \uc81c3\ucc28 \uc138\uacc4\ub300\uc804\uc774 \uc77c\uc5b4\ub0a0 \uc218 \uc788\ub2e4. (\ucc38\uace0: 2022\ub144 5\uc6d4 23\uc77c \uc81c\ucd9c \uc774\ud6c4 \uc778\ub3c4\uc758 \ube44\uc911\uc744 \ud06c\uac8c \uc904\uc600\uc2b5\ub2c8\ub2e4. \ucd5c\uadfc \uc774 \ud310\ub2e8\uc758 \uadfc\uac70\uac00 \ubb34\uc5c7\uc778\uc9c0 \uae30\uc5b5\uc774 \ub098\uc9c0 \uc54a\uc2b5\ub2c8\ub2e4. \uc8c4\uc1a1\ud569\ub2c8\ub2e4!)<\/p>\n<h3 style=\"text-align: left;\"><span class=\"ez-toc-section\" id=\"%E9%99%84%E8%A8%BB\"><\/span>\ucc38\uace0.<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: left;\">\uc5b4\uca0c\ub4e0 \uc801\uc5b4\ub3c4 \ub7ec\uc2dc\uc544-\uc6b0\ud06c\ub77c\uc774\ub098 \ubd84\uc7c1\uc774 L1\uacfc L2 \uc0ac\uc774\uc5d0 \uad6d\ud55c\ub420 \uac83\uc774\ub77c\ub294 \uc81c \uc608\uce21\uc740 \uc5ec\uc804\ud788 \ud2c0\ub9ac\uc9c0 \uc54a\uc558\uc2b5\ub2c8\ub2e4. \ubb3c\ub860 \uc9c0\uae08\uc740 \uc880 \ub354 \ubcf4\uc218\uc801\uc73c\ub85c \ubcc0\ud558\uace0 \uc788\uae30 \ub54c\ubb38\uc5d0 \ucd5c\uadfc \uac8c\uc2dc\ubb3c\uc5d0 \u201d\uc801\uc5b4\ub3c4 2026\ub144 \ub9d0\uae4c\uc9c0\u201d\ub77c\ub294 \uc2dc\ud55c\ubd80 \ubd80\uc0ac\ub97c \ud3ec\ud568\uc2dc\ucf30\uc2b5\ub2c8\ub2e4.<\/p>\n<p style=\"text-align: left;\">\ubbf8\uad6d\uc774 \uc720\ub7fd\uc5f0\ud569\uc744 \uc57d\ud654\uc2dc\ud0a4\ub824 \ud55c\ub2e4\ub294 \uc608\uce21\uc740 \ub300\uccb4\ub85c \uc0ac\uc2e4\ub85c \ud655\uc778\ub418\uc5c8\uc2b5\ub2c8\ub2e4.<\/p>\n<p style=\"text-align: left;\">","protected":false},"excerpt":{"rendered":"<p>\uc81c\ucd9c\ub428 2022\ub144 4\uc6d4 26\uc77c \uc6d0\ubcf8\uc774 \ubd84\uc2e4\ub418\uc5c8\uc2b5\ub2c8\ub2e4. \uc6b0\uc5f0\ud788 \ubc1c\uacac \ub41c \uc81c\ucd9c\ubb3c\uc5d0 \ub530\ub974\uba74 \ub7ec\uc2dc\uc544-\uc6b0\ud06c\ub77c\uc774\ub098 \uad6d\uacbd \uc7a5\ubcbd\uc5d0 \ub300\ud55c \ucd5c\ucd08\uc758 \uc608\uce21\uc740 2 \ub144\uc5d0 \uc774\ub8e8\uc5b4 \uc84c\uc74c\uc744 \uc2dc\uc0ac\ud569\ub2c8\ub2e4.<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[11],"tags":[],"class_list":["post-4310","post","type-post","status-publish","format-standard","hentry","category-2022war"],"_links":{"self":[{"href":"https:\/\/pppnet.net\/ko\/wp-json\/wp\/v2\/posts\/4310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pppnet.net\/ko\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pppnet.net\/ko\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pppnet.net\/ko\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pppnet.net\/ko\/wp-json\/wp\/v2\/comments?post=4310"}],"version-history":[{"count":2,"href":"https:\/\/pppnet.net\/ko\/wp-json\/wp\/v2\/posts\/4310\/revisions"}],"predecessor-version":[{"id":4529,"href":"https:\/\/pppnet.net\/ko\/wp-json\/wp\/v2\/posts\/4310\/revisions\/4529"}],"wp:attachment":[{"href":"https:\/\/pppnet.net\/ko\/wp-json\/wp\/v2\/media?parent=4310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pppnet.net\/ko\/wp-json\/wp\/v2\/categories?post=4310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pppnet.net\/ko\/wp-json\/wp\/v2\/tags?post=4310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}